{"id":2825,"date":"2022-06-08T14:00:41","date_gmt":"2022-06-08T18:00:41","guid":{"rendered":"https:\/\/presenceautochtone.ca\/le-fipa\/calendrier\/"},"modified":"2023-08-11T16:52:54","modified_gmt":"2023-08-11T20:52:54","slug":"calendrier","status":"publish","type":"page","link":"https:\/\/presenceautochtone.ca\/archives\/2025\/festival\/calendrier\/","title":{"rendered":"Calendrier"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":2822,"menu_order":55,"comment_status":"closed","ping_status":"closed","template":"templates\/calendrier-template.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2825","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Calendrier - Pr\u00e9sence Autochtone<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Calendrier - Pr\u00e9sence Autochtone\" \/>\n<meta property=\"og:url\" content=\"https:\/\/presenceautochtone.ca\/archives\/2025\/festival\/calendrier\/\" \/>\n<meta property=\"og:site_name\" content=\"Pr\u00e9sence Autochtone\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-11T20:52:54+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2025\\\/festival\\\/calendrier\\\/\",\"url\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2025\\\/festival\\\/calendrier\\\/\",\"name\":\"Calendrier - Pr\u00e9sence Autochtone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2025\\\/#website\"},\"datePublished\":\"2022-06-08T18:00:41+00:00\",\"dateModified\":\"2023-08-11T20:52:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2025\\\/festival\\\/calendrier\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2025\\\/festival\\\/calendrier\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2025\\\/festival\\\/calendrier\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2025\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Festival\",\"item\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2025\\\/festival\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Calendrier\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2025\\\/#website\",\"url\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2025\\\/\",\"name\":\"Pr\u00e9sence Autochtone\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2025\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Calendrier - Pr\u00e9sence Autochtone","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Calendrier - Pr\u00e9sence Autochtone","og_url":"https:\/\/presenceautochtone.ca\/archives\/2025\/festival\/calendrier\/","og_site_name":"Pr\u00e9sence Autochtone","article_modified_time":"2023-08-11T20:52:54+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/presenceautochtone.ca\/archives\/2025\/festival\/calendrier\/","url":"https:\/\/presenceautochtone.ca\/archives\/2025\/festival\/calendrier\/","name":"Calendrier - Pr\u00e9sence Autochtone","isPartOf":{"@id":"https:\/\/presenceautochtone.ca\/archives\/2025\/#website"},"datePublished":"2022-06-08T18:00:41+00:00","dateModified":"2023-08-11T20:52:54+00:00","breadcrumb":{"@id":"https:\/\/presenceautochtone.ca\/archives\/2025\/festival\/calendrier\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/presenceautochtone.ca\/archives\/2025\/festival\/calendrier\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/presenceautochtone.ca\/archives\/2025\/festival\/calendrier\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/presenceautochtone.ca\/archives\/2025\/"},{"@type":"ListItem","position":2,"name":"Festival","item":"https:\/\/presenceautochtone.ca\/archives\/2025\/festival\/"},{"@type":"ListItem","position":3,"name":"Calendrier"}]},{"@type":"WebSite","@id":"https:\/\/presenceautochtone.ca\/archives\/2025\/#website","url":"https:\/\/presenceautochtone.ca\/archives\/2025\/","name":"Pr\u00e9sence Autochtone","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/presenceautochtone.ca\/archives\/2025\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/presenceautochtone.ca\/archives\/2025\/wp-json\/wp\/v2\/pages\/2825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/presenceautochtone.ca\/archives\/2025\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/presenceautochtone.ca\/archives\/2025\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/presenceautochtone.ca\/archives\/2025\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/presenceautochtone.ca\/archives\/2025\/wp-json\/wp\/v2\/comments?post=2825"}],"version-history":[{"count":5,"href":"https:\/\/presenceautochtone.ca\/archives\/2025\/wp-json\/wp\/v2\/pages\/2825\/revisions"}],"predecessor-version":[{"id":9133,"href":"https:\/\/presenceautochtone.ca\/archives\/2025\/wp-json\/wp\/v2\/pages\/2825\/revisions\/9133"}],"up":[{"embeddable":true,"href":"https:\/\/presenceautochtone.ca\/archives\/2025\/wp-json\/wp\/v2\/pages\/2822"}],"wp:attachment":[{"href":"https:\/\/presenceautochtone.ca\/archives\/2025\/wp-json\/wp\/v2\/media?parent=2825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}