{"id":2831,"date":"2022-06-08T14:00:43","date_gmt":"2022-06-08T18:00:43","guid":{"rendered":"https:\/\/presenceautochtone.ca\/balado-rue-atateken\/"},"modified":"2023-04-13T18:29:24","modified_gmt":"2023-04-13T22:29:24","slug":"rue-atateken","status":"publish","type":"page","link":"https:\/\/presenceautochtone.ca\/archives\/2023\/rue-atateken\/","title":{"rendered":"Rue ATATEKEN"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":6,"comment_status":"closed","ping_status":"closed","template":"templates\/rue-atateken-template.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2831","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rue ATATEKEN - Pr\u00e9sence Autochtone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/presenceautochtone.ca\/archives\/2023\/rue-atateken\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rue ATATEKEN - Pr\u00e9sence Autochtone\" \/>\n<meta property=\"og:url\" content=\"https:\/\/presenceautochtone.ca\/archives\/2023\/rue-atateken\/\" \/>\n<meta property=\"og:site_name\" content=\"Pr\u00e9sence Autochtone\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-13T22:29:24+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/rue-atateken\\\/\",\"url\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/rue-atateken\\\/\",\"name\":\"Rue ATATEKEN - Pr\u00e9sence Autochtone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/#website\"},\"datePublished\":\"2022-06-08T18:00:43+00:00\",\"dateModified\":\"2023-04-13T22:29:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/rue-atateken\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/rue-atateken\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/rue-atateken\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rue ATATEKEN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/#website\",\"url\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/\",\"name\":\"Pr\u00e9sence Autochtone\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rue ATATEKEN - Pr\u00e9sence Autochtone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/presenceautochtone.ca\/archives\/2023\/rue-atateken\/","og_locale":"fr_FR","og_type":"article","og_title":"Rue ATATEKEN - Pr\u00e9sence Autochtone","og_url":"https:\/\/presenceautochtone.ca\/archives\/2023\/rue-atateken\/","og_site_name":"Pr\u00e9sence Autochtone","article_modified_time":"2023-04-13T22:29:24+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/presenceautochtone.ca\/archives\/2023\/rue-atateken\/","url":"https:\/\/presenceautochtone.ca\/archives\/2023\/rue-atateken\/","name":"Rue ATATEKEN - Pr\u00e9sence Autochtone","isPartOf":{"@id":"https:\/\/presenceautochtone.ca\/archives\/2023\/#website"},"datePublished":"2022-06-08T18:00:43+00:00","dateModified":"2023-04-13T22:29:24+00:00","breadcrumb":{"@id":"https:\/\/presenceautochtone.ca\/archives\/2023\/rue-atateken\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/presenceautochtone.ca\/archives\/2023\/rue-atateken\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/presenceautochtone.ca\/archives\/2023\/rue-atateken\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/presenceautochtone.ca\/archives\/2023\/"},{"@type":"ListItem","position":2,"name":"Rue ATATEKEN"}]},{"@type":"WebSite","@id":"https:\/\/presenceautochtone.ca\/archives\/2023\/#website","url":"https:\/\/presenceautochtone.ca\/archives\/2023\/","name":"Pr\u00e9sence Autochtone","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/presenceautochtone.ca\/archives\/2023\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/wp-json\/wp\/v2\/pages\/2831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/wp-json\/wp\/v2\/comments?post=2831"}],"version-history":[{"count":5,"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/wp-json\/wp\/v2\/pages\/2831\/revisions"}],"predecessor-version":[{"id":5785,"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/wp-json\/wp\/v2\/pages\/2831\/revisions\/5785"}],"wp:attachment":[{"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/wp-json\/wp\/v2\/media?parent=2831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}