{"id":2491,"date":"2022-05-06T12:25:58","date_gmt":"2022-05-06T16:25:58","guid":{"rendered":"https:\/\/presenceautochtone.ca\/?page_id=2491"},"modified":"2023-07-07T09:04:43","modified_gmt":"2023-07-07T13:04:43","slug":"communiques-de-presse","status":"publish","type":"page","link":"https:\/\/presenceautochtone.ca\/archives\/2023\/communiques-de-presse\/","title":{"rendered":"Communiqu\u00e9s de presse"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"templates\/communiques-template.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2491","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Communiqu\u00e9s de presse - Pr\u00e9sence Autochtone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/presenceautochtone.ca\/archives\/2023\/communiques-de-presse\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Communiqu\u00e9s de presse - Pr\u00e9sence Autochtone\" \/>\n<meta property=\"og:url\" content=\"https:\/\/presenceautochtone.ca\/archives\/2023\/communiques-de-presse\/\" \/>\n<meta property=\"og:site_name\" content=\"Pr\u00e9sence Autochtone\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-07T13:04:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/communiques-de-presse\\\/\",\"url\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/communiques-de-presse\\\/\",\"name\":\"Communiqu\u00e9s de presse - Pr\u00e9sence Autochtone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/#website\"},\"datePublished\":\"2022-05-06T16:25:58+00:00\",\"dateModified\":\"2023-07-07T13:04:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/communiques-de-presse\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/communiques-de-presse\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/communiques-de-presse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Communiqu\u00e9s de presse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/#website\",\"url\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/\",\"name\":\"Pr\u00e9sence Autochtone\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Communiqu\u00e9s de presse - Pr\u00e9sence Autochtone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/presenceautochtone.ca\/archives\/2023\/communiques-de-presse\/","og_locale":"fr_FR","og_type":"article","og_title":"Communiqu\u00e9s de presse - Pr\u00e9sence Autochtone","og_url":"https:\/\/presenceautochtone.ca\/archives\/2023\/communiques-de-presse\/","og_site_name":"Pr\u00e9sence Autochtone","article_modified_time":"2023-07-07T13:04:43+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/presenceautochtone.ca\/archives\/2023\/communiques-de-presse\/","url":"https:\/\/presenceautochtone.ca\/archives\/2023\/communiques-de-presse\/","name":"Communiqu\u00e9s de presse - Pr\u00e9sence Autochtone","isPartOf":{"@id":"https:\/\/presenceautochtone.ca\/archives\/2023\/#website"},"datePublished":"2022-05-06T16:25:58+00:00","dateModified":"2023-07-07T13:04:43+00:00","breadcrumb":{"@id":"https:\/\/presenceautochtone.ca\/archives\/2023\/communiques-de-presse\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/presenceautochtone.ca\/archives\/2023\/communiques-de-presse\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/presenceautochtone.ca\/archives\/2023\/communiques-de-presse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/presenceautochtone.ca\/archives\/2023\/"},{"@type":"ListItem","position":2,"name":"Communiqu\u00e9s de presse"}]},{"@type":"WebSite","@id":"https:\/\/presenceautochtone.ca\/archives\/2023\/#website","url":"https:\/\/presenceautochtone.ca\/archives\/2023\/","name":"Pr\u00e9sence Autochtone","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/presenceautochtone.ca\/archives\/2023\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/wp-json\/wp\/v2\/pages\/2491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/wp-json\/wp\/v2\/comments?post=2491"}],"version-history":[{"count":5,"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/wp-json\/wp\/v2\/pages\/2491\/revisions"}],"predecessor-version":[{"id":6814,"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/wp-json\/wp\/v2\/pages\/2491\/revisions\/6814"}],"wp:attachment":[{"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/wp-json\/wp\/v2\/media?parent=2491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}