{"id":9123,"date":"2023-08-11T15:30:08","date_gmt":"2023-08-11T19:30:08","guid":{"rendered":"https:\/\/presenceautochtone.ca\/?post_type=communiques&#038;p=9123"},"modified":"2023-08-11T15:30:08","modified_gmt":"2023-08-11T19:30:08","slug":"dimanche-13-aout-a-14-h-a-la-maison-du-developpement-durable-causerie-sur-la-protection-patrimoniale-en-territoire-autochtone","status":"publish","type":"communiques","link":"https:\/\/presenceautochtone.ca\/archives\/2023\/communiques\/dimanche-13-aout-a-14-h-a-la-maison-du-developpement-durable-causerie-sur-la-protection-patrimoniale-en-territoire-autochtone\/","title":{"rendered":"Dimanche 13 ao\u00fbt \u00e0 14 h \u00e0 la Maison du d\u00e9veloppement durable Causerie sur la protection patrimoniale en territoire autochtone"},"author":3,"template":"","class_list":["post-9123","communiques","type-communiques","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dimanche 13 ao\u00fbt \u00e0 14 h \u00e0 la Maison du d\u00e9veloppement durable Causerie sur la protection patrimoniale en territoire autochtone - Pr\u00e9sence Autochtone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/presenceautochtone.ca\/archives\/2023\/communiques\/dimanche-13-aout-a-14-h-a-la-maison-du-developpement-durable-causerie-sur-la-protection-patrimoniale-en-territoire-autochtone\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dimanche 13 ao\u00fbt \u00e0 14 h \u00e0 la Maison du d\u00e9veloppement durable Causerie sur la protection patrimoniale en territoire autochtone - Pr\u00e9sence Autochtone\" \/>\n<meta property=\"og:url\" content=\"https:\/\/presenceautochtone.ca\/archives\/2023\/communiques\/dimanche-13-aout-a-14-h-a-la-maison-du-developpement-durable-causerie-sur-la-protection-patrimoniale-en-territoire-autochtone\/\" \/>\n<meta property=\"og:site_name\" content=\"Pr\u00e9sence Autochtone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/communiques\\\/dimanche-13-aout-a-14-h-a-la-maison-du-developpement-durable-causerie-sur-la-protection-patrimoniale-en-territoire-autochtone\\\/\",\"url\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/communiques\\\/dimanche-13-aout-a-14-h-a-la-maison-du-developpement-durable-causerie-sur-la-protection-patrimoniale-en-territoire-autochtone\\\/\",\"name\":\"Dimanche 13 ao\u00fbt \u00e0 14 h \u00e0 la Maison du d\u00e9veloppement durable Causerie sur la protection patrimoniale en territoire autochtone - Pr\u00e9sence Autochtone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/#website\"},\"datePublished\":\"2023-08-11T19:30:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/communiques\\\/dimanche-13-aout-a-14-h-a-la-maison-du-developpement-durable-causerie-sur-la-protection-patrimoniale-en-territoire-autochtone\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/communiques\\\/dimanche-13-aout-a-14-h-a-la-maison-du-developpement-durable-causerie-sur-la-protection-patrimoniale-en-territoire-autochtone\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/communiques\\\/dimanche-13-aout-a-14-h-a-la-maison-du-developpement-durable-causerie-sur-la-protection-patrimoniale-en-territoire-autochtone\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Communiqu\u00e9s de presse\",\"item\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/communiques\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dimanche 13 ao\u00fbt \u00e0 14 h \u00e0 la Maison du d\u00e9veloppement durable Causerie sur la protection patrimoniale en territoire autochtone\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/#website\",\"url\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/\",\"name\":\"Pr\u00e9sence Autochtone\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dimanche 13 ao\u00fbt \u00e0 14 h \u00e0 la Maison du d\u00e9veloppement durable Causerie sur la protection patrimoniale en territoire autochtone - Pr\u00e9sence Autochtone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/presenceautochtone.ca\/archives\/2023\/communiques\/dimanche-13-aout-a-14-h-a-la-maison-du-developpement-durable-causerie-sur-la-protection-patrimoniale-en-territoire-autochtone\/","og_locale":"fr_FR","og_type":"article","og_title":"Dimanche 13 ao\u00fbt \u00e0 14 h \u00e0 la Maison du d\u00e9veloppement durable Causerie sur la protection patrimoniale en territoire autochtone - Pr\u00e9sence Autochtone","og_url":"https:\/\/presenceautochtone.ca\/archives\/2023\/communiques\/dimanche-13-aout-a-14-h-a-la-maison-du-developpement-durable-causerie-sur-la-protection-patrimoniale-en-territoire-autochtone\/","og_site_name":"Pr\u00e9sence Autochtone","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/presenceautochtone.ca\/archives\/2023\/communiques\/dimanche-13-aout-a-14-h-a-la-maison-du-developpement-durable-causerie-sur-la-protection-patrimoniale-en-territoire-autochtone\/","url":"https:\/\/presenceautochtone.ca\/archives\/2023\/communiques\/dimanche-13-aout-a-14-h-a-la-maison-du-developpement-durable-causerie-sur-la-protection-patrimoniale-en-territoire-autochtone\/","name":"Dimanche 13 ao\u00fbt \u00e0 14 h \u00e0 la Maison du d\u00e9veloppement durable Causerie sur la protection patrimoniale en territoire autochtone - Pr\u00e9sence Autochtone","isPartOf":{"@id":"https:\/\/presenceautochtone.ca\/archives\/2023\/#website"},"datePublished":"2023-08-11T19:30:08+00:00","breadcrumb":{"@id":"https:\/\/presenceautochtone.ca\/archives\/2023\/communiques\/dimanche-13-aout-a-14-h-a-la-maison-du-developpement-durable-causerie-sur-la-protection-patrimoniale-en-territoire-autochtone\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/presenceautochtone.ca\/archives\/2023\/communiques\/dimanche-13-aout-a-14-h-a-la-maison-du-developpement-durable-causerie-sur-la-protection-patrimoniale-en-territoire-autochtone\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/presenceautochtone.ca\/archives\/2023\/communiques\/dimanche-13-aout-a-14-h-a-la-maison-du-developpement-durable-causerie-sur-la-protection-patrimoniale-en-territoire-autochtone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/presenceautochtone.ca\/archives\/2023\/"},{"@type":"ListItem","position":2,"name":"Communiqu\u00e9s de presse","item":"https:\/\/presenceautochtone.ca\/archives\/2023\/communiques\/"},{"@type":"ListItem","position":3,"name":"Dimanche 13 ao\u00fbt \u00e0 14 h \u00e0 la Maison du d\u00e9veloppement durable Causerie sur la protection patrimoniale en territoire autochtone"}]},{"@type":"WebSite","@id":"https:\/\/presenceautochtone.ca\/archives\/2023\/#website","url":"https:\/\/presenceautochtone.ca\/archives\/2023\/","name":"Pr\u00e9sence Autochtone","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/presenceautochtone.ca\/archives\/2023\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/wp-json\/wp\/v2\/communiques\/9123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/wp-json\/wp\/v2\/communiques"}],"about":[{"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/wp-json\/wp\/v2\/types\/communiques"}],"author":[{"embeddable":true,"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":1,"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/wp-json\/wp\/v2\/communiques\/9123\/revisions"}],"predecessor-version":[{"id":9124,"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/wp-json\/wp\/v2\/communiques\/9123\/revisions\/9124"}],"wp:attachment":[{"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/wp-json\/wp\/v2\/media?parent=9123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}