{"id":2662,"date":"2022-05-31T04:06:59","date_gmt":"2022-05-31T08:06:59","guid":{"rendered":"https:\/\/presenceautochtone.ca\/?post_type=communiques&#038;p=2662"},"modified":"2022-06-02T10:18:03","modified_gmt":"2022-06-02T14:18:03","slug":"terres-en-vues-rend-hommage-au-chef-max-gros-louis","status":"publish","type":"communiques","link":"https:\/\/presenceautochtone.ca\/archives\/2023\/communiques\/terres-en-vues-rend-hommage-au-chef-max-gros-louis\/","title":{"rendered":"Cultures premi\u00e8res : Terres en vues annonce de nombreuses activit\u00e9s pour le Mois de l\u2019histoire autochtone"},"author":1,"template":"","class_list":["post-2662","communiques","type-communiques","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cultures premi\u00e8res : Terres en vues annonce de nombreuses activit\u00e9s pour le Mois de l\u2019histoire autochtone - Pr\u00e9sence Autochtone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/presenceautochtone.ca\/archives\/2023\/communiques\/terres-en-vues-rend-hommage-au-chef-max-gros-louis\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cultures premi\u00e8res : Terres en vues annonce de nombreuses activit\u00e9s pour le Mois de l\u2019histoire autochtone - Pr\u00e9sence Autochtone\" \/>\n<meta property=\"og:url\" content=\"https:\/\/presenceautochtone.ca\/archives\/2023\/communiques\/terres-en-vues-rend-hommage-au-chef-max-gros-louis\/\" \/>\n<meta property=\"og:site_name\" content=\"Pr\u00e9sence Autochtone\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-02T14:18:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/communiques\\\/terres-en-vues-rend-hommage-au-chef-max-gros-louis\\\/\",\"url\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/communiques\\\/terres-en-vues-rend-hommage-au-chef-max-gros-louis\\\/\",\"name\":\"Cultures premi\u00e8res : Terres en vues annonce de nombreuses activit\u00e9s pour le Mois de l\u2019histoire autochtone - Pr\u00e9sence Autochtone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/#website\"},\"datePublished\":\"2022-05-31T08:06:59+00:00\",\"dateModified\":\"2022-06-02T14:18:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/communiques\\\/terres-en-vues-rend-hommage-au-chef-max-gros-louis\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/communiques\\\/terres-en-vues-rend-hommage-au-chef-max-gros-louis\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/communiques\\\/terres-en-vues-rend-hommage-au-chef-max-gros-louis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Communiqu\u00e9s de presse\",\"item\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/communiques\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cultures premi\u00e8res : Terres en vues annonce de nombreuses activit\u00e9s pour le Mois de l\u2019histoire autochtone\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/#website\",\"url\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/\",\"name\":\"Pr\u00e9sence Autochtone\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cultures premi\u00e8res : Terres en vues annonce de nombreuses activit\u00e9s pour le Mois de l\u2019histoire autochtone - Pr\u00e9sence Autochtone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/presenceautochtone.ca\/archives\/2023\/communiques\/terres-en-vues-rend-hommage-au-chef-max-gros-louis\/","og_locale":"fr_FR","og_type":"article","og_title":"Cultures premi\u00e8res : Terres en vues annonce de nombreuses activit\u00e9s pour le Mois de l\u2019histoire autochtone - Pr\u00e9sence Autochtone","og_url":"https:\/\/presenceautochtone.ca\/archives\/2023\/communiques\/terres-en-vues-rend-hommage-au-chef-max-gros-louis\/","og_site_name":"Pr\u00e9sence Autochtone","article_modified_time":"2022-06-02T14:18:03+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/presenceautochtone.ca\/archives\/2023\/communiques\/terres-en-vues-rend-hommage-au-chef-max-gros-louis\/","url":"https:\/\/presenceautochtone.ca\/archives\/2023\/communiques\/terres-en-vues-rend-hommage-au-chef-max-gros-louis\/","name":"Cultures premi\u00e8res : Terres en vues annonce de nombreuses activit\u00e9s pour le Mois de l\u2019histoire autochtone - Pr\u00e9sence Autochtone","isPartOf":{"@id":"https:\/\/presenceautochtone.ca\/archives\/2023\/#website"},"datePublished":"2022-05-31T08:06:59+00:00","dateModified":"2022-06-02T14:18:03+00:00","breadcrumb":{"@id":"https:\/\/presenceautochtone.ca\/archives\/2023\/communiques\/terres-en-vues-rend-hommage-au-chef-max-gros-louis\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/presenceautochtone.ca\/archives\/2023\/communiques\/terres-en-vues-rend-hommage-au-chef-max-gros-louis\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/presenceautochtone.ca\/archives\/2023\/communiques\/terres-en-vues-rend-hommage-au-chef-max-gros-louis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/presenceautochtone.ca\/archives\/2023\/"},{"@type":"ListItem","position":2,"name":"Communiqu\u00e9s de presse","item":"https:\/\/presenceautochtone.ca\/archives\/2023\/communiques\/"},{"@type":"ListItem","position":3,"name":"Cultures premi\u00e8res : Terres en vues annonce de nombreuses activit\u00e9s pour le Mois de l\u2019histoire autochtone"}]},{"@type":"WebSite","@id":"https:\/\/presenceautochtone.ca\/archives\/2023\/#website","url":"https:\/\/presenceautochtone.ca\/archives\/2023\/","name":"Pr\u00e9sence Autochtone","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/presenceautochtone.ca\/archives\/2023\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/wp-json\/wp\/v2\/communiques\/2662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/wp-json\/wp\/v2\/communiques"}],"about":[{"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/wp-json\/wp\/v2\/types\/communiques"}],"author":[{"embeddable":true,"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":4,"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/wp-json\/wp\/v2\/communiques\/2662\/revisions"}],"predecessor-version":[{"id":2699,"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/wp-json\/wp\/v2\/communiques\/2662\/revisions\/2699"}],"wp:attachment":[{"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/wp-json\/wp\/v2\/media?parent=2662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}