{"id":7690,"date":"2023-07-12T11:33:42","date_gmt":"2023-07-12T15:33:42","guid":{"rendered":"https:\/\/presenceautochtone.ca\/?post_type=activites_culturelle&#038;p=7690"},"modified":"2023-08-04T00:14:56","modified_gmt":"2023-08-04T04:14:56","slug":"projection-gratuite-whale-rider","status":"publish","type":"activites_culturelle","link":"https:\/\/presenceautochtone.ca\/archives\/2023\/terres-en-vues\/activites-culturelles\/projection-gratuite-whale-rider\/","title":{"rendered":"WHALE RIDER"},"template":"","categories_activites":[11],"class_list":["post-7690","activites_culturelle","type-activites_culturelle","status-publish","hentry","categories_activites-en-personne"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WHALE RIDER - Pr\u00e9sence Autochtone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/presenceautochtone.ca\/archives\/2023\/terres-en-vues\/activites-culturelles\/projection-gratuite-whale-rider\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WHALE RIDER - Pr\u00e9sence Autochtone\" \/>\n<meta property=\"og:url\" content=\"https:\/\/presenceautochtone.ca\/archives\/2023\/terres-en-vues\/activites-culturelles\/projection-gratuite-whale-rider\/\" \/>\n<meta property=\"og:site_name\" content=\"Pr\u00e9sence Autochtone\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-04T04:14:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/terres-en-vues\\\/activites-culturelles\\\/projection-gratuite-whale-rider\\\/\",\"url\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/terres-en-vues\\\/activites-culturelles\\\/projection-gratuite-whale-rider\\\/\",\"name\":\"WHALE RIDER - Pr\u00e9sence Autochtone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/#website\"},\"datePublished\":\"2023-07-12T15:33:42+00:00\",\"dateModified\":\"2023-08-04T04:14:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/terres-en-vues\\\/activites-culturelles\\\/projection-gratuite-whale-rider\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/terres-en-vues\\\/activites-culturelles\\\/projection-gratuite-whale-rider\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/terres-en-vues\\\/activites-culturelles\\\/projection-gratuite-whale-rider\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WHALE RIDER\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/#website\",\"url\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/\",\"name\":\"Pr\u00e9sence Autochtone\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WHALE RIDER - Pr\u00e9sence Autochtone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/presenceautochtone.ca\/archives\/2023\/terres-en-vues\/activites-culturelles\/projection-gratuite-whale-rider\/","og_locale":"fr_FR","og_type":"article","og_title":"WHALE RIDER - Pr\u00e9sence Autochtone","og_url":"https:\/\/presenceautochtone.ca\/archives\/2023\/terres-en-vues\/activites-culturelles\/projection-gratuite-whale-rider\/","og_site_name":"Pr\u00e9sence Autochtone","article_modified_time":"2023-08-04T04:14:56+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/presenceautochtone.ca\/archives\/2023\/terres-en-vues\/activites-culturelles\/projection-gratuite-whale-rider\/","url":"https:\/\/presenceautochtone.ca\/archives\/2023\/terres-en-vues\/activites-culturelles\/projection-gratuite-whale-rider\/","name":"WHALE RIDER - Pr\u00e9sence Autochtone","isPartOf":{"@id":"https:\/\/presenceautochtone.ca\/archives\/2023\/#website"},"datePublished":"2023-07-12T15:33:42+00:00","dateModified":"2023-08-04T04:14:56+00:00","breadcrumb":{"@id":"https:\/\/presenceautochtone.ca\/archives\/2023\/terres-en-vues\/activites-culturelles\/projection-gratuite-whale-rider\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/presenceautochtone.ca\/archives\/2023\/terres-en-vues\/activites-culturelles\/projection-gratuite-whale-rider\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/presenceautochtone.ca\/archives\/2023\/terres-en-vues\/activites-culturelles\/projection-gratuite-whale-rider\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/presenceautochtone.ca\/archives\/2023\/"},{"@type":"ListItem","position":2,"name":"WHALE RIDER"}]},{"@type":"WebSite","@id":"https:\/\/presenceautochtone.ca\/archives\/2023\/#website","url":"https:\/\/presenceautochtone.ca\/archives\/2023\/","name":"Pr\u00e9sence Autochtone","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/presenceautochtone.ca\/archives\/2023\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/wp-json\/wp\/v2\/activites_culturelle\/7690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/wp-json\/wp\/v2\/activites_culturelle"}],"about":[{"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/wp-json\/wp\/v2\/types\/activites_culturelle"}],"version-history":[{"count":5,"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/wp-json\/wp\/v2\/activites_culturelle\/7690\/revisions"}],"predecessor-version":[{"id":8660,"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/wp-json\/wp\/v2\/activites_culturelle\/7690\/revisions\/8660"}],"wp:attachment":[{"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/wp-json\/wp\/v2\/media?parent=7690"}],"wp:term":[{"taxonomy":"categories_activites","embeddable":true,"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/wp-json\/wp\/v2\/categories_activites?post=7690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}