{"id":6935,"date":"2023-07-10T15:53:49","date_gmt":"2023-07-10T19:53:49","guid":{"rendered":"https:\/\/presenceautochtone.ca\/?post_type=artistes&#038;p=6935"},"modified":"2023-07-10T15:53:49","modified_gmt":"2023-07-10T19:53:49","slug":"there-are-spirits-in-the-forest","status":"publish","type":"artistes","link":"https:\/\/presenceautochtone.ca\/archives\/2023\/en\/artistes\/there-are-spirits-in-the-forest\/","title":{"rendered":"There are Spirits in the Forest"},"template":"","class_list":["post-6935","artistes","type-artistes","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>There are Spirits in the Forest - Pr\u00e9sence Autochtone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/presenceautochtone.ca\/archives\/2023\/en\/artistes\/there-are-spirits-in-the-forest\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"There are Spirits in the Forest - Pr\u00e9sence Autochtone\" \/>\n<meta property=\"og:url\" content=\"https:\/\/presenceautochtone.ca\/archives\/2023\/en\/artistes\/there-are-spirits-in-the-forest\/\" \/>\n<meta property=\"og:site_name\" content=\"Pr\u00e9sence Autochtone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/en\\\/artistes\\\/there-are-spirits-in-the-forest\\\/\",\"url\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/en\\\/artistes\\\/there-are-spirits-in-the-forest\\\/\",\"name\":\"There are Spirits in the Forest - Pr\u00e9sence Autochtone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/#website\"},\"datePublished\":\"2023-07-10T19:53:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/en\\\/artistes\\\/there-are-spirits-in-the-forest\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/en\\\/artistes\\\/there-are-spirits-in-the-forest\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/en\\\/artistes\\\/there-are-spirits-in-the-forest\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"There are Spirits in the Forest\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/#website\",\"url\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/\",\"name\":\"Pr\u00e9sence Autochtone\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/presenceautochtone.ca\\\/archives\\\/2023\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"There are Spirits in the Forest - Pr\u00e9sence Autochtone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/presenceautochtone.ca\/archives\/2023\/en\/artistes\/there-are-spirits-in-the-forest\/","og_locale":"en_US","og_type":"article","og_title":"There are Spirits in the Forest - Pr\u00e9sence Autochtone","og_url":"https:\/\/presenceautochtone.ca\/archives\/2023\/en\/artistes\/there-are-spirits-in-the-forest\/","og_site_name":"Pr\u00e9sence Autochtone","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/presenceautochtone.ca\/archives\/2023\/en\/artistes\/there-are-spirits-in-the-forest\/","url":"https:\/\/presenceautochtone.ca\/archives\/2023\/en\/artistes\/there-are-spirits-in-the-forest\/","name":"There are Spirits in the Forest - Pr\u00e9sence Autochtone","isPartOf":{"@id":"https:\/\/presenceautochtone.ca\/archives\/2023\/#website"},"datePublished":"2023-07-10T19:53:49+00:00","breadcrumb":{"@id":"https:\/\/presenceautochtone.ca\/archives\/2023\/en\/artistes\/there-are-spirits-in-the-forest\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/presenceautochtone.ca\/archives\/2023\/en\/artistes\/there-are-spirits-in-the-forest\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/presenceautochtone.ca\/archives\/2023\/en\/artistes\/there-are-spirits-in-the-forest\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/presenceautochtone.ca\/archives\/2023\/en\/"},{"@type":"ListItem","position":2,"name":"There are Spirits in the Forest"}]},{"@type":"WebSite","@id":"https:\/\/presenceautochtone.ca\/archives\/2023\/#website","url":"https:\/\/presenceautochtone.ca\/archives\/2023\/","name":"Pr\u00e9sence Autochtone","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/presenceautochtone.ca\/archives\/2023\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/en\/wp-json\/wp\/v2\/artistes\/6935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/en\/wp-json\/wp\/v2\/artistes"}],"about":[{"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/en\/wp-json\/wp\/v2\/types\/artistes"}],"version-history":[{"count":2,"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/en\/wp-json\/wp\/v2\/artistes\/6935\/revisions"}],"predecessor-version":[{"id":7326,"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/en\/wp-json\/wp\/v2\/artistes\/6935\/revisions\/7326"}],"wp:attachment":[{"href":"https:\/\/presenceautochtone.ca\/archives\/2023\/en\/wp-json\/wp\/v2\/media?parent=6935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}